{"id":142,"date":"2013-07-17T23:36:31","date_gmt":"2013-07-17T21:36:31","guid":{"rendered":"https:\/\/www.abueling.com\/blog\/?p=142"},"modified":"2021-03-17T14:44:45","modified_gmt":"2021-03-17T14:44:45","slug":"de-donde-viene-apellido","status":"publish","type":"post","link":"https:\/\/www.abueling.com\/blog\/de-donde-viene-apellido\/","title":{"rendered":"De d\u00f3nde viene tu apellido"},"content":{"rendered":"\n<p>\u00bfAlguna vez te has preguntado el <a href=\"https:\/\/www.abueling.com\/investigacion-genealogica\/estudio-antepasados-apellido\/precios-investigacion-genealogica-apellido\"><strong>origen de tu apellido<\/strong><\/a>?, \u00bfQu\u00e9 significado tiene?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><img decoding=\"async\" src=\"https:\/\/www.abueling.com\/blog\/wp-content\/uploads\/2013\/07\/060220131501-225x300.jpg\" alt=\"Libros ordenados en archivo\"\/><\/figure><\/div>\n\n\n\n<p>No es f\u00e1cil encontrar estas respuestas, pero puedes empezar intentando saber a qu\u00e9 categor\u00eda pertenece. Aqu\u00ed te indicamos algunas de ellas con algunos ejemplos clarificadores:<\/p>\n\n\n\n<p>Los <strong><a href=\"\/blog\/origen-apellidos\/\">apellidos Patron\u00edmicos<\/a><\/strong> proced\u00edan del nombre de pila del padre del nacido. Muchos de ellos se formaron a\u00f1adi\u00e9ndoles los sufijo \u201cez\u201d, \u201cis\u201d, \u201ciz\u201d\u2026 As\u00ed podemos encontrar, del nombre Mart\u00edn (Mart\u00ednez), de Fernando (Fern\u00e1ndez), de Sancho (S\u00e1nchez)\u2026 seguro que os suenan todos ellos.<\/p>\n\n\n\n<p>Los <strong>apellidos Topon\u00edmicos<\/strong> indicaban el lugar de nacimiento o de residencia de la persona. Se podr\u00eda tratar de una localidad, una regi\u00f3n, una edificaci\u00f3n o un accidente geogr\u00e1fico de la zona. Muchos de ellos usaban la preposici\u00f3n \u201dDe\u201d aunque con el tiempo se ha ido perdiendo y ya pocos lo mantienen. Por ejemplo \u201cLinares\u201d, \u201cde la Torre\u201d, \u201cdel Manzano\u201d, \u201cdel Valle\u201d\u2026<\/p>\n\n\n\n<p>Los que se formaron a partir de <strong>profesiones, ocupaciones o cargos sociales<\/strong>. Carnicero, Marqu\u00e9s, Jurado, Pastor, Herrero, Zapatero (Qu\u00e9 curioso llevar el apellido de la profesi\u00f3n de un <a href=\"\/investigacion-genealogica\">antepasado<\/a>\u2026)<\/p>\n\n\n\n<p>Tambi\u00e9n se formaban a partir de <strong>rasgos f\u00edsicos o del car\u00e1cter<\/strong> como pueden ser: Delgado, Amor, Rojo, Bello, Seco, Peque\u00f1o, Moreno, Leal, Cabez\u00f3n&#8230;<\/p>\n\n\n\n<p>Seguro que a todos nos suenan familiares apellidos que nos informan sobre las <strong>circunstancias del nacimiento<\/strong> como el mes de nacimiento, el santo que se celebraba ese d\u00eda, etc. o los que se utilizaban para identificar a reci\u00e9n nacidos de padres desconocidos, muchos de ellos con referencias religiosas (Diosdado, Iglesias, Exp\u00f3sito, De la Cruz, De Dios\u2026)<\/p>\n\n\n\n<p>Y por \u00faltimo los de origen incierto como los &nbsp;referentes a animales, vegetales u objetos. Posiblemente identificaban a las personas que los criaban, cultivaban o fabricaban, aqu\u00ed nos podemos encontrar: \u00c1guila, Botella, Palomo, Cebolla, Vaca, Zorrilla\u2026<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>\u00bf<\/strong><strong>Qu\u00e9 apellido conoces que te haya llamado m\u00e1s la atenci\u00f3n?&nbsp;\u00bfSabes ya el origen del tuyo?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Com\u00e9ntanos lo que quieras, y si te ha gustado el art\u00edculo, por favor comp\u00e1rtelo en tu red social favorita. \u00a1Gracias!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez te has preguntado el origen de tu apellido?, \u00bfQu\u00e9 significado tiene? No es f\u00e1cil encontrar estas respuestas, pero puedes empezar intentando saber a qu\u00e9 categor\u00eda pertenece. Aqu\u00ed te indicamos algunas de &hellip; <\/p>\n","protected":false},"author":2,"featured_media":143,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,108,63],"tags":[46,116,117,42],"class_list":["post-142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apellidos-2","category-curiosidades","category-curso-de-genealogia","tag-apellido","tag-de-donde-viene-el-apellido","tag-origen-apellidos","tag-origen-del-apellido"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/posts\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/comments?post=142"}],"version-history":[{"count":0,"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/posts\/142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/media\/143"}],"wp:attachment":[{"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/media?parent=142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/categories?post=142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abueling.com\/blog\/wp-json\/wp\/v2\/tags?post=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}